{"id":7210,"date":"2022-03-21T15:23:17","date_gmt":"2022-03-21T19:23:17","guid":{"rendered":"https:\/\/baycoast.bank\/sin-categorizar\/que-hacer-despues-de-una-filtracion-de-datos\/"},"modified":"2024-01-10T13:01:26","modified_gmt":"2024-01-10T18:01:26","slug":"que-hacer-despues-de-una-filtracion-de-datos","status":"publish","type":"post","link":"https:\/\/baycoast.bank\/es\/seguridad\/que-hacer-despues-de-una-filtracion-de-datos\/","title":{"rendered":"\u00bfQu\u00e9 hacer despu\u00e9s de una filtraci\u00f3n de datos?"},"content":{"rendered":"<div class=\"lazyblock-resource-hero-ZG1A8X wp-block-lazyblock-resource-hero\"><div class=\"noHero\" style=\"height: 10rem;\"><\/div>\n\n<div class=\"spacer\"><\/div>\n\n<div class=\"section\">\n\t<div class=\"smallWrapper gutenberg\">\n\t    \n\t    <div class=\"categories flex\" style=\"justify-content: flex-start;\">\n\t\t\t<div class=\"h6\" style=\"margin-right: 2rem;\"><a href=\"https:\/\/baycoast.bank\/resource\/seguridad\">Seguridad<\/a><\/div>\n\t\t\t\t\t\t\n\t\t\t<div class=\"primaryColor dot h6\" style=\"transform: scale(2.2); \">\u00b7<\/div>\n\n\t\t\t<div class=\"h6\" style=\"margin-left: 2rem;\">\t\t\t\t21 de marzo de 2022        \n\t\t\t<\/div>\n\t\t<\/div>\n\t    \n\t    <h1 class=\"h2 blue bgWhite\" style=\"max-width: 50rem\">\u00bfQu\u00e9 hacer despu\u00e9s de una filtraci\u00f3n de datos?<\/h1>\n\t    \n\t    <hr style=\"margin-bottom: 7rem;\">\n\t  \n\t<\/div>\n\t\n\t<div class=\"wrapper\" style=\"justify-content: center; max-width: 90rem;\">\n\t\t<div style=\"width: 100%; position: relative;\">\n\t\t\t<img decoding=\"async\" src=\"https:\/\/baycoast.bank\/wp-content\/uploads\/2022\/03\/What-to-do-after-a-Data-Breach.jpg\" role=\"img\" aria-label=\"\u00bfQu\u00e9 hacer despu\u00e9s de una filtraci\u00f3n de datos?\" style=\"width: 100%; height: auto;\" \/>\n  \t\t<\/div>\n\t<\/div>\n<\/div>\n\n          <\/div><div class=\"lazyblock-interior-content-2jkKVd wp-block-lazyblock-interior-content\"><div class=\"spacer\"><\/div>\n\n<div class=\"section\">\n\t<div class=\"paddedWrapper\">\n\t\t<div class=\"wrapper flex gutenberg\" style=\"justify-content: center;\">\n\n\t\t\t\n\t\t\t<div class=\"smallWrapper gutenberg\">\n\t\t\t\n\t\t\t\t<div class=\"h3\">Vivimos una din\u00e1mica era digital. Aunque las ventajas de la tecnolog\u00eda aportan grandes beneficios y eficiencia a nuestras vidas, tambi\u00e9n pueden suponer graves riesgos a la seguridad. <\/div>\n\t\t\t  \n\t\t\t  \t<hr style=\"margin-bottom: 5rem;\">\n\t\t\t\t\n\t\t\t\t\n\n<p class=\"wp-block-paragraph\">Los delitos relacionados con las computadoras est\u00e1n en ascenso y tienen como blanco a los consumidores y a las empresas por igual. Es de extrema importancia proteger nuestra informaci\u00f3n personal y financiera de las amenazas cibern\u00e9ticas, especialmente en lo que concierne al robo de identidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Muchos de nosotros tenemos alg\u00fan tipo de protecci\u00f3n, como seguridad con cortafuegos y software contra programas de malware, con el prop\u00f3sito de evitar que los piratas inform\u00e1ticos elijan nuestras computadoras y logren acceso no autorizado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero hasta las mejores protecciones pueden fracasar contra un ciberataque. Entre los datos que pudieran verse comprometidos en un ataque pudieran incluirse:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Nombres de usuario y contrase\u00f1as<\/li>\n\n\n\n<li>Direcciones de email<\/li>\n\n\n\n<li>N\u00fameros de tel\u00e9fono y domicilios residenciales<\/li>\n\n\n\n<li>Fechas de nacimiento<\/li>\n\n\n\n<li>N\u00fameros del Seguro Social<\/li>\n\n\n\n<li>N\u00fameros de licencia de conducir<\/li>\n\n\n\n<li>N\u00fameros de tarjetas de cr\u00e9dito o de d\u00e9bito<\/li>\n\n\n\n<li>Informaci\u00f3n de cuentas bancarias<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00bfQu\u00e9 pueden hacer los individuos y las empresas para reducir el impacto de una filtraci\u00f3n de datos? Federal Trade Commission (FTC) recomienda seguir los siguientes pasos.<\/strong><\/p>\n\n\n\n<div class=\"wp-block-stackable-spacer stk-block-spacer stk--no-padding stk-block stk-817a25e\" data-block-id=\"817a25e\"><style>.stk-817a25e{height:15px !important}<\/style><\/div>\n\n\n\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block stk-cb374fd\" data-block-id=\"cb374fd\"><style>.stk-cb374fd{margin-bottom:0px !important}.stk-cb374fd .stk-block-heading__text{color:var(--stk-global-color-3828,#18428f) !important}<\/style><h3 class=\"stk-block-heading__text has-text-color has-stk-global-color-3828-color\"><strong>PARA CONSUMIDORES IMPACTADOS POR UNA FILTRACI\u00d3N DE DATOS<\/strong><\/h3><\/div>\n\n\n\n<div class=\"wp-block-stackable-spacer stk-block-spacer stk--no-padding stk-block stk-d8ed0ed\" data-block-id=\"d8ed0ed\"><style>.stk-d8ed0ed{height:15px !important}<\/style><\/div>\n\n\n\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block stk-922583a\" data-block-id=\"922583a\"><style>.stk-922583a .stk-block-heading__text{color:var(--stk-global-color-63884,#fbad18) !important}<\/style><h4 class=\"stk-block-heading__text has-text-color has-stk-global-color-63884-color\"><strong>1) Comun\u00edcate con tu banco de inmediato<\/strong><\/h4><\/div>\n\n\n\n<ul class=\"wp-block-list\" type=\"1\">\n<li>Revisa todas tus cuentas para detectar cualquier actividad inusual. <\/li>\n\n\n\n<li>Repasa regularmente tus estados de cuenta para detectar actividades potencialmente fraudulentas.<\/li>\n\n\n\n<li>Reporta de inmediato cualquier actividad inusual.<\/li>\n<\/ul>\n\n\n\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block stk-1dd9998\" data-block-id=\"1dd9998\"><style>.stk-1dd9998 .stk-block-heading__text{color:var(--stk-global-color-63884,#fbad18) !important}<\/style><h4 class=\"stk-block-heading__text has-text-color has-stk-global-color-63884-color\"><strong>2) Rep\u00f3rtalo<\/strong><\/h4><\/div>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Si eres v\u00edctima de un robo de identidad, presenta un reporte policial y un reporte de robo de identidad ante la Federal Trade Commission en IdentityTheft.gov.<\/li>\n\n\n\n<li>Esto genera un reporte legal de robo y ayudar\u00e1 en caso de que alguien intente usar tu n\u00famero de Seguro Social para cometer un fraude. <\/li>\n<\/ul>\n\n\n\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block stk-75ca4f1\" data-block-id=\"75ca4f1\"><style>.stk-75ca4f1 .stk-block-heading__text{color:var(--stk-global-color-63884,#fbad18) !important}<\/style><h4 class=\"stk-block-heading__text has-text-color has-stk-global-color-63884-color\"><strong>3) Presenta una alerta de fraude en los reportes de cr\u00e9dito<\/strong><\/h4><\/div>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Presenta una alerta de fraude comun\u00edcandote con cualquiera de las tres oficinas de cr\u00e9dito: Equifax, Experian o TransUnion.\n<ul class=\"wp-block-list\">\n<li>No necesitas comunicarte con las tres. La oficina de cr\u00e9dito con la que te hayas comunicado informar\u00e1 a las otras dos de que presentaste una alerta de fraude en tu registro crediticio.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>Una alerta de fraude requiere que los acreedores potenciales se comuniquen contigo, el consumidor, para obtener permiso de abrir cuentas nuevas o l\u00edneas de cr\u00e9dito.<\/li>\n\n\n\n<li>Cuando presentas una alerta de fraude, puedes obtener una copia gratis de tu reporte de cr\u00e9dito de cada una de las tres oficinas de cr\u00e9dito.<\/li>\n\n\n\n<li>Una alerta de fraude dura un a\u00f1o, despu\u00e9s del cual puedes renovarla.\n<ul class=\"wp-block-list\">\n<li>Las alertas de fraude extendidas est\u00e1n disponibles pero solo si te han robado la identidad, has presentado un reporte policial y has completado un reporte de robo de identidad ante la FTC en IdentityTheft.com<\/li>\n\n\n\n<li>Cuando has presentado una alerta de fraude extendida, se te permite un reporte de cr\u00e9dito gratis de cada una de las oficinas de cr\u00e9dito dos veces al a\u00f1o a partir del momento en que presentaste la alerta.<\/li>\n\n\n\n<li>Una alerta de fraude extendida dura siete a\u00f1os.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>Para ambos tipos de alertas de fraude el costo es gratuito.<\/li>\n<\/ul>\n\n\n\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block stk-e873101\" data-block-id=\"e873101\"><style>.stk-e873101 .stk-block-heading__text{color:var(--stk-global-color-63884,#fbad18) !important}<\/style><h4 class=\"stk-block-heading__text has-text-color has-stk-global-color-63884-color\"><strong>4) Establece una congelaci\u00f3n de cr\u00e9dito en los reportes de cr\u00e9dito<\/strong><\/h4><\/div>\n\n\n\n<ul class=\"wp-block-list\">\n<li>La congelaci\u00f3n de cr\u00e9dito restringe el acceso a tu cuenta, para que t\u00fa, u otros, no puedan abrir cuentas nuevas en tu nombre mientres est\u00e9 congelada. <\/li>\n\n\n\n<li>Puedes suprimir la congelaci\u00f3n de cr\u00e9dito en forma temporal si surgen circunstancias donde necesites solicitar cr\u00e9dito.<\/li>\n\n\n\n<li>Para presentar una congelaci\u00f3n de cr\u00e9dito, debes comunicarte con cada una de las tres oficinas de cr\u00e9dito: Equifax, Experian y TransUnion.<\/li>\n<\/ul>\n\n\n\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block stk-cc17251\" data-block-id=\"cc17251\"><style>.stk-cc17251 .stk-block-heading__text{color:var(--stk-global-color-63884,#fbad18) !important}<\/style><h4 class=\"stk-block-heading__text has-text-color has-stk-global-color-63884-color\"><strong>5) Controla tu reporte de cr\u00e9dito cada a\u00f1o<\/strong><\/h4><\/div>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Los consumidores tienen derecho por ley a un reporte de cr\u00e9dito anual de cada una de las oficinas de cr\u00e9dito una vez al a\u00f1o.<\/li>\n\n\n\n<li>Revisa tus reportes cada a\u00f1o para asegurarte de que tu informaci\u00f3n crediticia es veraz y est\u00e1 actualizada.<\/li>\n\n\n\n<li>Las oficinas de cr\u00e9dito ofrecen un <a href=\"https:\/\/www.annualcreditreport.com\/index.action\" target=\"_blank\" rel=\"noreferrer noopener\">sitio web centralizado y autorizado<\/a> para pedir reportes de cr\u00e9dito gratis, o puedes llamar al 1-877-322-8228.<\/li>\n<\/ul>\n\n\n\n<div class=\"wp-block-stackable-spacer stk-block-spacer stk--no-padding stk-block stk-56d6b0f\" data-block-id=\"56d6b0f\"><style>.stk-56d6b0f{height:25px !important}<\/style><\/div>\n\n\n\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block stk-ae7f453\" data-block-id=\"ae7f453\"><h3 class=\"stk-block-heading__text\"><strong>PARA EMPRESAS IMPACTADAS POR UNA FILTRACI\u00d3N DE DATOS<\/strong><\/h3><\/div>\n\n\n\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block stk-74fa1f9\" data-block-id=\"74fa1f9\"><style>.stk-74fa1f9 .stk-block-heading__text{color:var(--stk-global-color-63884,#fbad18) !important}<\/style><h4 class=\"stk-block-heading__text has-text-color has-stk-global-color-63884-color\"><strong>1) Operaciones seguras<\/strong><\/h4><\/div>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Asegura las areas f\u00edsicas potencialmente relacionadas con la violaci\u00f3n de datos. <\/li>\n\n\n\n<li>Vigila cuidadosamente todos los puntos de entrada y salida.<\/li>\n\n\n\n<li>Asegura y cierra bajo llave estas \u00e1reas, restringe el acceso y, de ser necesario, cambia los c\u00f3digos de acceso.<\/li>\n\n\n\n<li>Actualiza las credenciales y contrase\u00f1as para usuarios autorizados.<\/li>\n\n\n\n<li>Si un pirata inform\u00e1tico rob\u00f3 credenciales, pon nuevas en su lugar, incluso si las herramientas del pirata inform\u00e1tico se eliminaron.<\/li>\n\n\n\n<li>Moviliza a tu equipo interno de respuesta a filtraciones para prevenir p\u00e9rdidas de datos adicionales.\n<ul class=\"wp-block-list\">\n<li>Dependiendo del tama\u00f1o y la naturaleza de tu empresa, tu equipo interno de respuesta podr\u00eda incluir servicios forenses, jur\u00eddicos, seguridad de la informaci\u00f3n, tecnolog\u00eda de la informaci\u00f3n, operaciones, recursos humanos y administraci\u00f3n.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block stk-0cddad0\" data-block-id=\"0cddad0\"><style>.stk-0cddad0 .stk-block-heading__text{color:var(--stk-global-color-63884,#fbad18) !important}<\/style><h4 class=\"stk-block-heading__text has-text-color has-stk-global-color-63884-color\"><strong>2) Repara las vulnerabilidades<\/strong><\/h4><\/div>\n\n\n\n<ul class=\"wp-block-list\">\n<li>De inmediato, quita de la l\u00ednea el equipo afectado.<\/li>\n\n\n\n<li>Verifica con proveedores de servicios externos para asegurarte de que ellos no se vieron afectados.<\/li>\n\n\n\n<li>Trabaja con expertos forenses:\n<ul class=\"wp-block-list\">\n<li>Determina qui\u00e9n tuvo acceso a la informaci\u00f3n en el momento de la filtraci\u00f3n de datos.<\/li>\n\n\n\n<li>Verifica el tipo de informaci\u00f3n comprometida y la cantidad de personas impactadas.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block stk-281b042\" data-block-id=\"281b042\"><style>.stk-281b042 .stk-block-heading__text{color:var(--stk-global-color-63884,#fbad18) !important}<\/style><h4 class=\"stk-block-heading__text has-text-color has-stk-global-color-63884-color\"><strong>3) Ten un plan de comunicaciones<\/strong><\/h4><\/div>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Si a\u00fan no lo has hecho, crea un plan completo que  incluya todas las partes afectadas.\n<ul class=\"wp-block-list\">\n<li>Esto incluye empleados, clientes, inversionistas, socios de negocios y accionistas.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>No retengas detalles clave sobre la filtraci\u00f3n de datos que pudieran ayudar a que los consumidores se protejan a s\u00ed mismos.<\/li>\n\n\n\n<li>No comparta en p\u00fablico cualquier informaci\u00f3n que pudiera poner a los consumidores en m\u00e1s riesgo.<\/li>\n<\/ul>\n\n\n\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block stk-ee8fbb6\" data-block-id=\"ee8fbb6\"><style>.stk-ee8fbb6 .stk-block-heading__text{color:var(--stk-global-color-63884,#fbad18) !important}<\/style><h4 class=\"stk-block-heading__text has-text-color has-stk-global-color-63884-color\"><strong>4) Notifique a las partes apropiadas<\/strong><\/h4><\/div>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Esto incluye a su departamento de polic\u00eda local.\n<ul class=\"wp-block-list\">\n<li>Reporte su situaci\u00f3n y el riesgo potencial para el robo de identidad.<\/li>\n\n\n\n<li>Mientras m\u00e1s pronto tengan conocimiento las fuerzas del cumplimiento de la ley, m\u00e1s eficaces pueden ser para prestar ayuda.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>Para m\u00e1s ayuda para investigar cuando la informaci\u00f3n se ve comprometida, comun\u00edcate con tu oficina local del FBI o el U. S. Secret Service.<\/li>\n<\/ul>\n\n\n\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block stk-d8a0b1f\" data-block-id=\"d8a0b1f\"><style>.stk-d8a0b1f .stk-block-heading__text{color:var(--stk-global-color-63884,#fbad18) !important}<\/style><h4 class=\"stk-block-heading__text has-text-color has-stk-global-color-63884-color\"><strong>5) \u00bfLa filtraci\u00f3n de informaci\u00f3n involucr\u00f3 los archivos m\u00e9dicos?<\/strong><\/h4><\/div>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Verifica si est\u00e1s cubierto por la Regla de Notificaci\u00f3n de Filtraci\u00f3n de Salud (Health Breach Notification Rule). De ser el caso, debes notificarle a la FTC y, en algunas instancias, a los medios de comunicaci\u00f3n.<\/li>\n\n\n\n<li>Para recursos adicionales respecto a las violaciones de datos m\u00e9dicos, <a href=\"https:\/\/www.ftc.gov\/business-guidance\/resources\/complying-ftcs-health-breach-notification-rule-0\" target=\"_blank\" rel=\"noopener\">visita este sitio web.<\/a><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Para conocer m\u00e1s acerca de c\u00f3mo responder despu\u00e9s de una filtraci\u00f3n de datos, visita el sitio web de la Federal Trade Commission en<a href=\"https:\/\/www.ftc.gov\/.\" target=\"_blank\" rel=\"noreferrer noopener\"> ftc.gov.<\/a><\/strong><\/p>\n\n\n\t\t\t<\/div>\n\n\t\t<\/div>\n\t<\/div>\n<\/div> <\/div>","protected":false},"excerpt":{"rendered":"<p>\u00bfQu\u00e9 pueden hacer los individuos y las empresas para reducir el impacto de una filtraci\u00f3n de datos? La Federal Trade Commission (FTC) recomienda los siguientes pasos.<\/p>\n","protected":false},"author":13,"featured_media":6365,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[111],"class_list":["post-7210","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-seguridad"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/baycoast.bank\/wp-content\/uploads\/2022\/03\/What-to-do-after-a-Data-Breach.jpg",1573,920,false],"thumbnail":["https:\/\/baycoast.bank\/wp-content\/uploads\/2022\/03\/What-to-do-after-a-Data-Breach-150x150.jpg",150,150,true],"medium":["https:\/\/baycoast.bank\/wp-content\/uploads\/2022\/03\/What-to-do-after-a-Data-Breach-300x175.jpg",300,175,true],"medium_large":["https:\/\/baycoast.bank\/wp-content\/uploads\/2022\/03\/What-to-do-after-a-Data-Breach-768x449.jpg",768,449,true],"large":["https:\/\/baycoast.bank\/wp-content\/uploads\/2022\/03\/What-to-do-after-a-Data-Breach-1024x599.jpg",1024,599,true],"1536x1536":["https:\/\/baycoast.bank\/wp-content\/uploads\/2022\/03\/What-to-do-after-a-Data-Breach-1536x898.jpg",1536,898,true],"2048x2048":["https:\/\/baycoast.bank\/wp-content\/uploads\/2022\/03\/What-to-do-after-a-Data-Breach.jpg",1573,920,false]},"post_excerpt_stackable_v2":"<p>\u00bfQu\u00e9 pueden hacer los individuos y las empresas para reducir el impacto de una filtraci\u00f3n de datos? La Federal Trade Commission (FTC) recomienda los siguientes pasos.<\/p>\n","category_list_v2":"<a href=\"https:\/\/baycoast.bank\/es\/.\/seguridad\/\" rel=\"category tag\">Seguridad<\/a>","author_info_v2":{"name":"","url":"https:\/\/baycoast.bank\/es\/author\/"},"comments_num_v2":"0 comentarios","publishpress_future_action":{"enabled":false,"date":"2026-07-22 12:08:31","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/baycoast.bank\/es\/wp-json\/wp\/v2\/posts\/7210","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/baycoast.bank\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/baycoast.bank\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/baycoast.bank\/es\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/baycoast.bank\/es\/wp-json\/wp\/v2\/comments?post=7210"}],"version-history":[{"count":0,"href":"https:\/\/baycoast.bank\/es\/wp-json\/wp\/v2\/posts\/7210\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/baycoast.bank\/es\/wp-json\/wp\/v2\/media\/6365"}],"wp:attachment":[{"href":"https:\/\/baycoast.bank\/es\/wp-json\/wp\/v2\/media?parent=7210"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/baycoast.bank\/es\/wp-json\/wp\/v2\/categories?post=7210"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}