{"id":7298,"date":"2022-03-29T09:00:00","date_gmt":"2022-03-29T13:00:00","guid":{"rendered":"https:\/\/baycoast.bank\/sin-categorizar\/protege-tu-informacion-financiera-de-los-ciberdelitos\/"},"modified":"2024-01-10T13:01:25","modified_gmt":"2024-01-10T18:01:25","slug":"protege-tu-informacion-financiera-de-los-ciberdelitos","status":"publish","type":"post","link":"https:\/\/baycoast.bank\/es\/seguridad\/protege-tu-informacion-financiera-de-los-ciberdelitos\/","title":{"rendered":"Protege tu informaci\u00f3n financiera de los ciberdelitos"},"content":{"rendered":"<div class=\"lazyblock-resource-hero-Z1sT827 wp-block-lazyblock-resource-hero\"><div class=\"noHero\" style=\"height: 10rem;\"><\/div>\n\n<div class=\"spacer\"><\/div>\n\n<div class=\"section\">\n\t<div class=\"smallWrapper gutenberg\">\n\t    \n\t    <div class=\"categories flex\" style=\"justify-content: flex-start;\">\n\t\t\t<div class=\"h6\" style=\"margin-right: 2rem;\"><a href=\"https:\/\/baycoast.bank\/resource\/seguridad\">Seguridad<\/a><\/div>\n\t\t\t\t\t\t\n\t\t\t<div class=\"primaryColor dot h6\" style=\"transform: scale(2.2); \">\u00b7<\/div>\n\n\t\t\t<div class=\"h6\" style=\"margin-left: 2rem;\">\t\t\t\t29 de marzo de 2022        \n\t\t\t<\/div>\n\t\t<\/div>\n\t    \n\t    <h1 class=\"h2 blue bgWhite\" style=\"max-width: 50rem\">Protege tu informaci\u00f3n financiera de los ciberdelitos<\/h1>\n\t    \n\t    <hr style=\"margin-bottom: 7rem;\">\n\t  \n\t<\/div>\n\t\n\t<div class=\"wrapper\" style=\"justify-content: center; max-width: 90rem;\">\n\t\t<div style=\"width: 100%; position: relative;\">\n\t\t\t<img decoding=\"async\" src=\"https:\/\/baycoast.bank\/wp-content\/uploads\/2022\/03\/Protect-Financial-Information.jpg\" role=\"img\" aria-label=\"Protege tu informaci\u00f3n financiera de los ciberdelitos\" style=\"width: 100%; height: auto;\" \/>\n  \t\t<\/div>\n\t<\/div>\n<\/div>\n\n          <\/div><div class=\"lazyblock-interior-content-Z2uJC3T wp-block-lazyblock-interior-content\"><div class=\"spacer\"><\/div>\n\n<div class=\"section\">\n\t<div class=\"paddedWrapper\">\n\t\t<div class=\"wrapper flex gutenberg\" style=\"justify-content: center;\">\n\n\t\t\t\n\t\t\t<div class=\"smallWrapper gutenberg\">\n\t\t\t\n\t\t\t\t<div class=\"h3\"><\/div>\n\t\t\t  \n\t\t\t  \t<hr style=\"margin-bottom: 5rem;\">\n\t\t\t\t\n\t\t\t\t\n\n<p> Los ciberdelitos \u2014que incluyen hackeo, phishing y software malicioso (malware)\u2014 buscan acceder a informaci\u00f3n personal sensible con el prop\u00f3sito de robarte dinero a ti o a otros en tu nombre.<\/p>\n\n\n\n<p>En esta era de la informaci\u00f3n, el ciberdelito es siempre una amenaza, pero existen algunas maneras sencillas de mantener tu informaci\u00f3n y tu dinero seguros. Con los siguientes consejos, puedes autoprotegerte de los delincuentes en l\u00ednea.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Evita los enlaces<\/h4>\n\n\n\n<p>Simplemente porque un correo electr\u00f3nico parezca provenir de una fuente conocida, no significa que sea real. Cuando recibas un correo electr\u00f3nico que parece venir de tu banco, compa\u00f1\u00eda de tarjeta de cr\u00e9dito o tienda en l\u00ednea favorita, no des clic en los enlaces que incluya. En lugar de eso, mejor empieza una nueva sesi\u00f3n en el sitio web de esa compa\u00f1\u00eda. Los estafadores tratan de enga\u00f1arte con enlaces de email falsos para que ingreses tu informaci\u00f3n en su p\u00e1gina falsa, d\u00e1ndoles as\u00ed acceso a tus cuentas verdaderas. Si tienes dudas acerca del origen verdadero de un correo electr\u00f3nico, puedes llamar directamente a la compa\u00f1\u00eda para verificar si es aut\u00e9ntico.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Protege tu computadora<\/h4>\n\n\n\n<p>Instala en tu computadora hogare\u00f1a software de confianza antivirus y antimalware, y aseg\u00farate de actualizar ese software a medida que surgen nuevas amenazas. Haz escaneos regulares para detectar programas esp\u00eda y maliciosos que pudieran acechar en segundo plano con el fin de capturar tu informaci\u00f3n financiera personal.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Asegura tus dispositivos m\u00f3viles<\/h4>\n\n\n\n<p>Tu tel\u00e9fono inteligente o tu tableta tienen protecciones s\u00f3lidas, pero su portabilidad tambi\u00e9n los vuelve vulnerables. Nunca ingreses tu informaci\u00f3n personal cuando est\u00e9s en una red de WiFi p\u00fablica, ya que hay piratas inform\u00e1ticos que podr\u00edan estar observ\u00e1ndote. No descargues aplicaciones m\u00f3viles a menos que conf\u00edes en la fuente. Aseg\u00farate de que proteger las contrase\u00f1as de tus dispositivos, para el caso de que los pierdas o te los roben. No te gustar\u00eda que un desconocido obtenga acceso a tus cuentas financieras.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Navega con cuidado<\/h4>\n\n\n\n<p>Solo tu informaci\u00f3n personal en sitios web si sabes que son seguros. \u00bfC\u00f3mo sabes si un sitio web es seguro? La direcci\u00f3n del sitio web debe comenzar con \u00abhttps\u00bb en lugar del usual \u00abhttp\u00bb, o tal vez puedes ver el s\u00edmbolo del candado al comienzo de la barra de direcci\u00f3n. Si no puedes constatar estos signos de seguridad, tu informaci\u00f3n podr\u00eda estar expuesta a robos.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Cuidado con las llamadas telef\u00f3nicas<\/h4>\n\n\n\n<p>Ninguna organizaci\u00f3n financiera respetable te pedir\u00e1 tu contrase\u00f1a ni ning\u00fan otro dato personal por tel\u00e9fono. Si alguien que dice trabajar para tu banco o compa\u00f1\u00eda de tarjeta de cr\u00e9dito te pide ese tipo de informaci\u00f3n, cu\u00e9lgales. Luego puedes buscar el n\u00famero de tel\u00e9fono verdadero de la compa\u00f1\u00eda y llamarles para verificar. Les interesar\u00e1 saber si alguien ha querido hacerse pasar por ellos. Lo mismo ocurre con el correo electr\u00f3nico; no conf\u00edes en mensajes donde te piden que env\u00edes informaci\u00f3n personal por medios electr\u00f3nicos.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Refuerza tus contrase\u00f1as<\/h4>\n\n\n\n<p>Puede resultar tentador usar una contrase\u00f1a memorable para todas tus cuentas en l\u00ednea, pero eso deja vulnerables a todas tus cuentas si una de las compa\u00f1\u00edas llegara a sufrir una violaci\u00f3n de datos. En lugar de eso, escoge contrase\u00f1as fuertes para cada cuenta y c\u00e1mbialas con frecuencia. Tal vez necesites usar un programa o extensi\u00f3n de navegador para crear y recordar muchas contrase\u00f1as distintas.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Atento con tus cuentas<\/h4>\n\n\n\n<p>La mayor\u00eda de las compa\u00f1\u00edas financieras tienen procedimientos para detectar los fraudes, pero no por eso debes dejar de vigilar tus cuentas personalmente. Mantente atento a transacciones irregulares o aquellas que no recuerdes haber hecho. Comun\u00edcate con la compa\u00f1\u00eda en cuanto observes algo inusual. Mientras m\u00e1s r\u00e1pido detectes el problema, m\u00e1s f\u00e1cil ser\u00e1 resolverlo.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Mant\u00e9n tu software actualizado<\/h4>\n\n\n\n<p>\u00bfSab\u00edas que las versiones m\u00e1s antiguas de Windows (XP, Vista, 7, or 8) e Internet Explorer ya no cuenta con soporte de Microsoft? Si usas estos productos, podr\u00edas estar poniendo en riesgo tu informaci\u00f3n. <strong>El software que ya no cuenta con soporte es vulnerable a los ciberataques que pueden llevar a p\u00e9rdida de datos en tu computadora, robo de identidad, robo de credenciales para la banca electr\u00f3nica (nombre de usuario\/contrase\u00f1a, etc.) o una cantidad de otros impactos negativos. <\/strong>Algunas de estas amenazas hasta pueden usar tu computadora para lanzar m\u00e1s ataques a gente que conoces o incluso al p\u00fablico en general. Dada la gravedad de estos riesgos, deber\u00edas considerar seriamente actualizar lo antes posible tu computadora a una que opere con una versi\u00f3n de Windows (10 u 11) con soporte, junto con la versi\u00f3n m\u00e1s actualizada de Microsoft Edge. <\/p>\n\n\n\n<p>Mantener actualizado tu software para protegerte tambi\u00e9n se extiende m\u00e1s all\u00e1 de los productos Microsoft. Aseg\u00farate siempre de que mantienes actualizado todo el software que operes en tu computadora, ya que estas aplicaciones tambi\u00e9n pueden ser explotadas si no se colocan los parches de seguridad correspondientes. Estas incluyen aplicaciones tales como Adobe Acrobat Reader, Oracle Java y navegadores de Internet de terceros (p. ej., Google Chrome y Mozilla Firefox). Asimismo, es altamente recomendable que instales y mantengas actualizado un software contra virus y malware que tenga un funci\u00f3n de autoprotecci\u00f3n. <\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Bloquea tus dispositivos<\/h4>\n\n\n\n<div class=\"wp-block-stackable-image stk-block-image stk-block stk-11ed3e0\" data-block-id=\"11ed3e0\"><style>.stk-11ed3e0{max-width:60% !important;margin-right:auto !important;margin-bottom:0px !important;margin-left:0px !important}<\/style><a class=\"stk-link\" href=\"https:\/\/baycoast.bank\/wp-content\/uploads\/2022\/03\/en_us_step_by_step_lock_everything_up-1-scaled.jpg\" title=\"Lock Up Your Devices Infographic\" target=\"_blank\" rel=\"noreferrer noopener\"><div class=\"stk-img-wrapper stk-image--shape-stretch\"><img decoding=\"async\" class=\"stk-img wp-image-7752\" src=\"https:\/\/baycoast.bank\/wp-content\/uploads\/2022\/03\/en_us_step_by_step_lock_everything_up-1-scaled.jpg\" width=\"991\" height=\"2560\" srcset=\"https:\/\/baycoast.bank\/wp-content\/uploads\/2022\/03\/en_us_step_by_step_lock_everything_up-1-scaled.jpg 991w, https:\/\/baycoast.bank\/wp-content\/uploads\/2022\/03\/en_us_step_by_step_lock_everything_up-1-116x300.jpg 116w, https:\/\/baycoast.bank\/wp-content\/uploads\/2022\/03\/en_us_step_by_step_lock_everything_up-1-768x1983.jpg 768w, https:\/\/baycoast.bank\/wp-content\/uploads\/2022\/03\/en_us_step_by_step_lock_everything_up-1-595x1536.jpg 595w, https:\/\/baycoast.bank\/wp-content\/uploads\/2022\/03\/en_us_step_by_step_lock_everything_up-1-793x2048.jpg 793w\" sizes=\"(max-width: 991px) 100vw, 991px\" \/><\/div><\/a><\/div>\n\n\n\n<p class=\"has-text-align-left\"><a href=\"https:\/\/baycoast.bank\/wp-content\/uploads\/2022\/03\/en_us_step_by_step_lock_everything_up-1-scaled.jpg\">(Pulsa en la imagen para ampliarla)<\/a><br\/>Fuente: KnowBe4<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">En BayCoast Bank trabajamos con empe\u00f1o para mantener segura tu informaci\u00f3n financiera personal.<\/h4>\n\n\n\n<p><a href=\"https:\/\/baycoast.bank\/es\/acerca-de-nosotros\/servicio-al-cliente\/\">Ponte en contacto con nosotros<\/a> con cualquier duda o pregunta que tengas y trabajaremos contigo para resolverlas.<\/p>\n\n\n\n<p>Tambi\u00e9n puedes consultar nuestra <a href=\"https:\/\/baycoast.bank\/security\/\">p\u00e1gina de recursos en l\u00ednea<\/a> para obtener informaci\u00f3n \u00fatil acerca de la seguridad cibern\u00e9tica, seguridad en correos electr\u00f3nicos e Internet, consejos para prevenir el robo de identidad y m\u00e1s.<\/p>\n\n\n\n<div class=\"wp-block-stackable-spacer stk-block-spacer stk--no-padding stk-block stk-e2000ec\" data-block-id=\"e2000ec\"><style>.stk-e2000ec{height:20px !important}<\/style><\/div>\n\n\n\n<div class=\"wp-block-stackable-divider stk-block-divider stk-block stk-d480552\" data-block-id=\"d480552\"><style>.stk-d480552{margin-bottom:40px !important}<\/style><hr class=\"stk-block-divider__hr\" \/><\/div>\n\n\n\n<p>Puedes consultar a continuaci\u00f3n una serie de gu\u00edas e informaci\u00f3n sobre ciberseguridad.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Gu\u00edas \u00fatiles<\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/baycoast.bank\/wp-content\/uploads\/2020\/08\/CyberBusiness.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Gu\u00eda de seguridad cibern\u00e9tica para empresas<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/baycoast.bank\/wp-content\/uploads\/2020\/08\/CyberSecurity.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Guia de seguridad cibern\u00e9tica para clientes de instituciones financieras (consumidores)<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/baycoast.bank\/wp-content\/uploads\/2020\/08\/FDIC_Guide-min.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">FDIC Consumer News &#8211; Gu\u00eda de seguridad cibern\u00e9tica para clientes de bancos<\/a>:<strong> <\/strong>Lo que pueden hacer los consumidores&#8230;y lo que hacen los bancos y reguladores&#8230;para ayudar a prevenir fraudes y robos en l\u00ednea<\/li>\n\n\n\n<li><a href=\"http:\/\/staysafeonline.org\/\" target=\"_blank\" rel=\"noopener\">Consejos de seguridad por Internet<\/a> <\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\">Contactos importantes<\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"http:\/\/fdic.gov\/\" target=\"_blank\" rel=\"noopener\">FDIC.gov<\/a><\/li>\n\n\n\n<li><a href=\"http:\/\/ftc.gov\/\" target=\"_blank\" rel=\"noopener\">FTC.gov<\/a> &#8211; Federal Trade Commission <\/li>\n\n\n\n<li><a href=\"http:\/\/onguardonline.gov\/\" target=\"_blank\" rel=\"noopener\">OnguardOnline.gov<\/a><\/li>\n\n\n\n<li><a href=\"http:\/\/identitytheft.gov\/\" target=\"_blank\" rel=\"noopener\">IdentityTheft.gov<\/a><\/li>\n\n\n\n<li><a href=\"http:\/\/fbi.gov\/\" target=\"_blank\" rel=\"noopener\">FBI.gov<\/a><\/li>\n\n\n\n<li><a href=\"http:\/\/experian.com\/\" target=\"_blank\" rel=\"noopener\">Experian.com<\/a><\/li>\n\n\n\n<li><a href=\"http:\/\/transunion.com\/\" target=\"_blank\" rel=\"noopener\">Transunion.com<\/a><\/li>\n\n\n\n<li><a href=\"http:\/\/equifax.com\/\" target=\"_blank\" rel=\"noopener\">Equifax.com<\/a><\/li>\n\n\n\n<li><a href=\"http:\/\/staysafeonline.org\/\" target=\"_blank\" rel=\"noopener\">StaySafeOnline.org<\/a><\/li>\n<\/ul>\n\n\n\n<div class=\"wp-block-stackable-spacer stk-block-spacer stk--no-padding stk-block stk-bd668ef\" data-block-id=\"bd668ef\"><style>.stk-bd668ef{height:15px !important}<\/style><\/div>\n\n\n\n<h4 class=\"wp-block-heading\">T\u00e9rminos habituales pertenecientes a la ciberseguridad.<\/h4>\n\n\n\n<div class=\"wp-block-stackable-spacer stk-block-spacer stk--no-padding stk-block stk-109fd4f\" data-block-id=\"109fd4f\"><style>.stk-109fd4f{height:15px !important}<\/style><\/div>\n\n\n\n<h4 class=\"wp-block-heading\">Software malicioso <\/h4>\n\n\n\n<p>La palabra inglesa \u00abmalware\u00bb es un t\u00e9rmino breve que equivale a \u00absoftware malicioso\u00bb, el cual hace alusi\u00f3n a los programas de software dise\u00f1ados para hacer da\u00f1o o cometer acciones indeseadas en un sistema de computaci\u00f3n. Los ejemplos comunes de \u00abmalware\u00bb, incluyen virus, gusanos inform\u00e1ticos, troyanos y programas esp\u00eda. <\/p>\n\n\n\n<p>Por ejemplo, los virus pueden causar estragos en el disco duro de una computadora al borrar archivos o informaci\u00f3n del directorio. Los programas esp\u00eda pueden reunir datos del sistema de un usuario sin que el usuario lo sepa. Esto puede incluir cualquier cosa, desde p\u00e1ginas web o visitas del usuario hasta informaci\u00f3n personal, tales como n\u00fameros de tarjetas de cr\u00e9dito. <\/p>\n\n\n\n<p>Los usuarios pueden combatir el software malicioso instalando programas antivirus y antiesp\u00edas, los cuales buscan y destruyen los programas maliciosos. Los programas contra virus y esp\u00edas se pueden comprar dondequiera que se vendan productos inform\u00e1ticos.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Phishing<\/h4>\n\n\n\n<p>Existe un nuevo tipo de pirater\u00eda inform\u00e1tica llamada \u00abphishing\u00bb. En un caso t\u00edpico, recibes un correo electr\u00f3nico que parece provenir de una compa\u00f1\u00eda respetable que t\u00fa reconoces y con la cual tienes relaci\u00f3n, digamos, tu instituci\u00f3n financiera. En algunos casos, el correo electr\u00f3nico hasta parece provenir de una agencia gubernamental, incluida una de las agencias federales reglamentarias de instituciones financieras. En una estafa de \u00abphishing\u00bb puedes ser redirigido a un sitio web falso, cuya apariencia puede ser exactamente igual a la del verdadero. Una vez en dicho sitio web falso, se te puede pedir que proporciones tu n\u00famero de Seguro Social, tus n\u00fameros de cuenta, tus contrase\u00f1as u otros datos que se usen para identificarte. Cuando les das esa informaci\u00f3n, los perpetradores del fraude pueden empezar a acceder tus cuentas y suplantar tu identidad. Nunca contestes directamente ni hagas clic en un enlace en respuesta a alg\u00fan email que te pida tu informaci\u00f3n personal o financiera. Acu\u00e9rdate: Tu banco nunca se comunicar\u00e1 contigo asi como \u00abde la nada\u00bb para pedirte informaci\u00f3n financiera personal.<\/p>\n\n\n\n<p><strong>No respondas a esos mensajes de correo electr\u00f3nico que te amenazan con terribles consecuencias<\/strong> a menos que les valides tu informaci\u00f3n de inmediato. Ponte en contacto con la compa\u00f1\u00eda para confirmar la validez del correo electr\u00f3nico utilizando un n\u00famero de tel\u00e9fono o direcci\u00f3n electr\u00f3nica cuya veracidad conozcas.<\/p>\n\n\n\n<p>Cuando presentes informaci\u00f3n financiera en un sitio web, busca el candado o el \u00edcono de la llave en la parte inferior de tu navegador y aseg\u00farate de que la direcci\u00f3n de Internet empieza con \u00abhttps\u00bb. Esto te se\u00f1ala que tu informaci\u00f3n est\u00e1 segura durante la trasmisi\u00f3n.<\/p>\n\n\n\n<p>Usa software antivirus y mantenlo actualizado. Los softwares antivirus y cortafuegos pueden protegerte de que inadvertidamente aceptes archivos de registro de teclas o \u00abkey logger\u00bb. Busca software antivirus que reconozca los virus actuales, as\u00ed como otros m\u00e1s viejos.<\/p>\n\n\n\n<p>Mant\u00e9n el sistema operativo de tu computadora al d\u00eda y descarga los parches de seguridad. Estos parches para tu sistema operativo cierran los agujeros de los que se aprovechan y explotan los piratas inform\u00e1ticos.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Smishing<\/h4>\n\n\n\n<p>Parecido al phishing, el \u00absmishing\u00bb hace uso de los mensajes de texto de tu tel\u00e9fono para enviar el anzuelo para que divulgues tu informaci\u00f3n personal. Este gancho(el m\u00e9todo usado para \u00abcapturar\u00bb tu informaci\u00f3n) en un mensaje de texto puede ser el URL de un sitio web; no obstante, se ha vuelto m\u00e1s com\u00fan ver un n\u00famero de tel\u00e9fono que se conecta con un sistema de respuesta de voz automatizado.<\/p>\n\n\n\n<p>El mensaje de \u00absmishing\u00bb usualmente contiene algo que necesita tu \u00abatenci\u00f3n inmediata\u00bb. Algunos ejemplos incluyen: <\/p>\n\n\n\n<p>1. \u00abEstamos confirmando que te inscribiste a nuestro servicio de citas. Se te cobrar\u00e1n $2 diarios a menos que canceles tu pedido en este URL: <strong>www.?????.com<\/strong>.\u00bb<\/p>\n\n\n\n<p>2. \u00ab(<strong>Nombre de un popular banco en l\u00ednea<\/strong>) desea confirmar que acabas de comprar una computadora por $1,500 en (<strong>nombre de una popular compa\u00f1\u00eda de computadoras<\/strong>). Visita <strong>www.?????.com<\/strong> si no hiciste esta compra en l\u00ednea\u00bb.<\/p>\n\n\n\n<p>3. \u00ab(<strong>Nombre de una instituci\u00f3n financiera<\/strong>): Tu cuenta se ha suspendido. Comun\u00edcate al <strong>xxx-xxx-xxxx<\/strong> de inmediato para reactivarla\u00bb.<\/p>\n\n\n\n<p>Este gancho pudiera tener el aspecto leg\u00edtimo de un sitio web que te pide que ingreses tu informaci\u00f3n financiera personal, como el n\u00famero de tu tarjeta de cr\u00e9dito\/d\u00e9bito, tuc\u00f3digo CVV (que se encuentra al reverso de tu tarjeta), el PIN de tu tarjeta de ATM, tu n\u00famero de Seguro Social, tu email y otros datos personales. Si el gancho es un n\u00famero de tel\u00e9fono, por lo general te dirige a un sistema de voz automatizado que se oye leg\u00edtimo, similar a los sistemas de voz de respuesta que usan muchas instituciones financieras, que te van a pedir la misma informaci\u00f3n personal.<\/p>\n\n\n\n<p><strong>No respondas a mensajes de texto, direcciones de sitios web, ni n\u00fameros de tel\u00e9fono que te advierten de consecuencias terribles<\/strong> si no les validas tu informacion de inmediato. Ponte en contacto con la compa\u00f1\u00eda para confirmar la validez de su petici\u00f3n usando un n\u00famero de tel\u00e9fono o direcci\u00f3n electr\u00f3nica que sabes que es ver\u00eddico. <\/p>\n\n\n\t\t\t<\/div>\n\n\t\t<\/div>\n\t<\/div>\n<\/div> <\/div>","protected":false},"excerpt":{"rendered":"<p>En esta era de la informaci\u00f3n, el ciberdelito es siempre una amenaza, pero existen algunas maneras sencillas de mantener tu informaci\u00f3n y tu dinero seguros.<\/p>\n","protected":false},"author":13,"featured_media":6363,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[111],"class_list":["post-7298","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-seguridad"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/baycoast.bank\/wp-content\/uploads\/2022\/03\/Protect-Financial-Information.jpg",1573,920,false],"thumbnail":["https:\/\/baycoast.bank\/wp-content\/uploads\/2022\/03\/Protect-Financial-Information-150x150.jpg",150,150,true],"medium":["https:\/\/baycoast.bank\/wp-content\/uploads\/2022\/03\/Protect-Financial-Information-300x175.jpg",300,175,true],"medium_large":["https:\/\/baycoast.bank\/wp-content\/uploads\/2022\/03\/Protect-Financial-Information-768x449.jpg",768,449,true],"large":["https:\/\/baycoast.bank\/wp-content\/uploads\/2022\/03\/Protect-Financial-Information-1024x599.jpg",1024,599,true],"1536x1536":["https:\/\/baycoast.bank\/wp-content\/uploads\/2022\/03\/Protect-Financial-Information-1536x898.jpg",1536,898,true],"2048x2048":["https:\/\/baycoast.bank\/wp-content\/uploads\/2022\/03\/Protect-Financial-Information.jpg",1573,920,false]},"post_excerpt_stackable_v2":"<p>En esta era de la informaci\u00f3n, el ciberdelito es siempre una amenaza, pero existen algunas maneras sencillas de mantener tu informaci\u00f3n y tu dinero seguros.<\/p>\n","category_list_v2":"<a href=\"https:\/\/baycoast.bank\/es\/.\/seguridad\/\" rel=\"category tag\">Seguridad<\/a>","author_info_v2":{"name":"","url":"https:\/\/baycoast.bank\/es\/author\/"},"comments_num_v2":"0 comentarios","publishpress_future_action":{"enabled":false,"date":"2026-05-20 10:31:22","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/baycoast.bank\/es\/wp-json\/wp\/v2\/posts\/7298","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/baycoast.bank\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/baycoast.bank\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/baycoast.bank\/es\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/baycoast.bank\/es\/wp-json\/wp\/v2\/comments?post=7298"}],"version-history":[{"count":0,"href":"https:\/\/baycoast.bank\/es\/wp-json\/wp\/v2\/posts\/7298\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/baycoast.bank\/es\/wp-json\/wp\/v2\/media\/6363"}],"wp:attachment":[{"href":"https:\/\/baycoast.bank\/es\/wp-json\/wp\/v2\/media?parent=7298"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/baycoast.bank\/es\/wp-json\/wp\/v2\/categories?post=7298"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}