{"id":12050,"date":"2024-06-28T06:12:00","date_gmt":"2024-06-28T10:12:00","guid":{"rendered":"https:\/\/baycoast.bank\/percepcoes\/baycoast-bank-anuncia-as-promocoes-de-almeida-creador-e-lapointe\/"},"modified":"2024-07-25T14:19:53","modified_gmt":"2024-07-25T18:19:53","slug":"baycoast-bank-anuncia-as-promocoes-de-almeida-creador-e-lapointe","status":"publish","type":"post","link":"https:\/\/baycoast.bank\/pt-pt\/sala-de-imprensa\/baycoast-bank-anuncia-as-promocoes-de-almeida-creador-e-lapointe\/","title":{"rendered":"BayCoast Bank anuncia as promo\u00e7\u00f5es de Almeida, Creador e Lapointe"},"content":{"rendered":"<div class=\"lazyblock-resource-hero-Z2ujvPt wp-block-lazyblock-resource-hero\"><div class=\"noHero\" style=\"height: 10rem;\"><\/div>\n\n<div class=\"spacer\"><\/div>\n\n<div class=\"section\">\n\t<div class=\"smallWrapper gutenberg\">\n\t    \n\t    <div class=\"categories flex\" style=\"justify-content: flex-start;\">\n\t\t\t<div class=\"h6\" style=\"margin-right: 2rem;\"><a href=\"https:\/\/baycoast.bank\/resource\/sala-de-imprensa\">Sala de imprensa<\/a><\/div>\n\t\t\t\t\t\t\n\t\t\t<div class=\"primaryColor dot h6\" style=\"transform: scale(2.2); \">\u00b7<\/div>\n\n\t\t\t<div class=\"h6\" style=\"margin-left: 2rem;\">\t\t\t\t28 de Junho, 2024        \n\t\t\t<\/div>\n\t\t<\/div>\n\t    \n\t    <h1 class=\"h2 blue bgWhite\" style=\"max-width: 50rem\">BayCoast Bank anuncia as promo\u00e7\u00f5es de Almeida, Creador e Lapointe<\/h1>\n\t    \n\t    <hr style=\"margin-bottom: 7rem;\">\n\t  \n\t<\/div>\n\t\n\t<div class=\"wrapper\" style=\"justify-content: center; max-width: 90rem;\">\n\t\t<div style=\"width: 100%; position: relative;\">\n\t\t\t<img decoding=\"async\" src=\"https:\/\/baycoast.bank\/wp-content\/uploads\/2024\/06\/Promotion-Press-Release-Header-1-1.jpg\" role=\"img\" aria-label=\"BayCoast Bank anuncia as promo\u00e7\u00f5es de Almeida, Creador e Lapointe\" style=\"width: 100%; height: auto;\" \/>\n  \t\t<\/div>\n\t<\/div>\n<\/div>\n\n          <\/div><div class=\"lazyblock-interior-content-KQzCs wp-block-lazyblock-interior-content\"><div class=\"spacer\"><\/div>\n\n<div class=\"section\">\n\t<div class=\"paddedWrapper\">\n\t\t<div class=\"wrapper flex gutenberg\" style=\"justify-content: center;\">\n\n\t\t\t\n\t\t\t<div class=\"smallWrapper gutenberg\">\n\t\t\t\n\t\t\t\t<div class=\"h3\"> Junta-te a n\u00f3s e felicita os membros da nossa equipa pelas suas merecidas promo\u00e7\u00f5es!<\/div>\n\t\t\t  \n\t\t\t  \t<hr style=\"margin-bottom: 5rem;\">\n\t\t\t\t\n\t\t\t\t\n\n<p>SWANSEA, SOMERSET, BERKLEY, FALL RIVER, MA &#8211; O BayCoast Bank<a href=\"http:\/\/baycoast.bank\">(baycoast.bank<\/a>), um banco de poupan\u00e7a comunit\u00e1rio de longa data que serve as pessoas e as empresas da costa sul de Massachusetts e Rhode Island, tem o prazer de anunciar tr\u00eas promo\u00e7\u00f5es importantes.<\/p>\n\n\n\n<p><strong>Sally Almeida<\/strong>, residente em Somerset, Massachusetts, foi elevada ao cargo de Diretora de Recursos Humanos do BayCoast Bank. As suas responsabilidades incluem o processamento de sal\u00e1rios e relat\u00f3rios relacionados para o Banco e as suas subsidi\u00e1rias, a manuten\u00e7\u00e3o de registos precisos dos funcion\u00e1rios, a facilita\u00e7\u00e3o do processo de compensa\u00e7\u00e3o anual para mais de 500 funcion\u00e1rios, a coordena\u00e7\u00e3o da integra\u00e7\u00e3o de novas contrata\u00e7\u00f5es, bem como a manuten\u00e7\u00e3o da conformidade com as leis e regulamentos de emprego federais, estatais e locais. Almeida ocupou anteriormente o cargo de Generalista de Recursos Humanos.  <\/p>\n\n\n\n<p>Almeida, que possui um diploma de associado do Bristol Community College, tamb\u00e9m se formou na New England School for Financial Studies no Babson College. Possui certifica\u00e7\u00f5es de Recursos Humanos de N\u00edvel 1 e N\u00edvel 2 da Associated Industries of Massachusetts. Almeida iniciou a sua carreira no sector financeiro como caixa do BankFive em 1993. Mais tarde, passou para os Recursos Humanos em 2011, onde permaneceu at\u00e9 \u00e0 sua contrata\u00e7\u00e3o pela BayCoast em 2019.   <\/p>\n\n\n\n<p>Almeida dedica-se \u00e0 sua comunidade, servindo como co-capit\u00e3 da equipa da American Cancer Society&#8217;s Relay For Life of Greater Fall River. \u00c9 volunt\u00e1ria na organiza\u00e7\u00e3o h\u00e1 mais de 12 anos em mem\u00f3ria do seu pai, que faleceu de cancro do pulm\u00e3o em 2011. <\/p>\n\n\n\n<p><strong>Monica C. Creador<\/strong>, de Fall River, Massachusetts, foi promovida a Directora de Administra\u00e7\u00e3o de Sistemas do BayCoast Bank. Nesta fun\u00e7\u00e3o, administra e gere v\u00e1rios sistemas de Tecnologia da Informa\u00e7\u00e3o (TI), incluindo a instala\u00e7\u00e3o de caixas interactivas (ITMs) e caixas autom\u00e1ticas (ATMs) do BayCoast, sistemas antiv\u00edrus\/antimalware e gest\u00e3o de dispositivos m\u00f3veis. Trabalha tamb\u00e9m em estreita colabora\u00e7\u00e3o com o pessoal do Helpdesk de TI do banco, apoiando os pedidos de servi\u00e7os t\u00e9cnicos. Anteriormente, foi Administradora de Sistemas.   <\/p>\n\n\n\n<p>Creador iniciou a sua carreira no sector financeiro em 2006 como Associado do Servi\u00e7o de Apoio ao Cliente. Posteriormente, ocupou cargos como Supervisor de Atendimento ao Cliente, T\u00e9cnico de Helpdesk de TI e Gerente de Helpdesk de TI. <\/p>\n\n\n\n<p>Licenciada em Administra\u00e7\u00e3o de Empresas pela Universidade de Massachusetts, Dartmouth, Creador est\u00e1 atualmente a tirar um mestrado em Gest\u00e3o de Tecnologias da Informa\u00e7\u00e3o.<\/p>\n\n\n\n<p><strong>Alex W. Lapointe<\/strong>, residente em Berkley, Massachusetts, foi promovido ao cargo de Diretor de Opera\u00e7\u00f5es Comerciais do BayCoast Bank. Nesta fun\u00e7\u00e3o, trabalha com a equipa de Opera\u00e7\u00f5es Comerciais para manter a carteira de empr\u00e9stimos comerciais do Banco e responder \u00e0s quest\u00f5es dos clientes.<br\/>Trabalha tamb\u00e9m para melhorar a efici\u00eancia do Banco, a fim de melhorar a experi\u00eancia geral do cliente. <\/p>\n\n\n\n<p>Lapointe ingressou no BayCoast Bank em 2017 como especialista em opera\u00e7\u00f5es comerciais. Tamb\u00e9m trabalhou como l\u00edder de equipa de opera\u00e7\u00f5es comerciais e analista de investidores\/conformidade. <\/p>\n\n\n\n<p>Licenciado em Ci\u00eancias Pol\u00edticas pela Universidade de Massachusetts, Dartmouth, Alex \u00e9 um dos formandos de 2019 do programa Leadership South Coast.<\/p>\n\n\n\n<p>&#8220;Tenho orgulho de anunciar o avan\u00e7o de tr\u00eas profissionais em nossa comunidade BayCoast&#8221;, disse Nicholas M. Christ, Presidente e CEO do BayCoast Bank. &#8220;Sally, Monica e Alex s\u00e3o indiv\u00edduos dedicados que demonstram um forte compromisso com a nossa comunidade e a fam\u00edlia BayCoast. Felicitamo-los pelas suas promo\u00e7\u00f5es e desejamos-lhes sucesso futuro&#8221;. <\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Sobre o BayCoast Bank<\/h4>\n\n\n\n<p>O <strong>BayCoast Bank<\/strong> \u00e9 um banco comunit\u00e1rio de longa data que fornece produtos e servi\u00e7os financeiros \u00e0s pessoas e empresas na costa sul de Massachusetts e Rhode Island atrav\u00e9s de 25 ag\u00eancias e escrit\u00f3rios de produ\u00e7\u00e3o de empr\u00e9stimos, com mais em breve. O Banco oferece uma fam\u00edlia de servi\u00e7os financeiros completos atrav\u00e9s das suas subsidi\u00e1rias: <strong>BayCoast Mortgage, BayCoast Financial Services, BayCoast Insurance, Plimoth Investment Advisors e Priority Funding<\/strong>. Para obter mais informa\u00e7\u00f5es, visita<a href=\"http:\/\/baycoast.bank\"> baycoast.bank <\/a>ou liga para 508-678-7641.  <\/p>\n\n\n\t\t\t<\/div>\n\n\t\t<\/div>\n\t<\/div>\n<\/div> <\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":17,"featured_media":11966,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[205],"class_list":["post-12050","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sala-de-imprensa"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/baycoast.bank\/wp-content\/uploads\/2024\/06\/Promotion-Press-Release-Header-1-1.jpg",600,298,false],"thumbnail":["https:\/\/baycoast.bank\/wp-content\/uploads\/2024\/06\/Promotion-Press-Release-Header-1-1-150x150.jpg",150,150,true],"medium":["https:\/\/baycoast.bank\/wp-content\/uploads\/2024\/06\/Promotion-Press-Release-Header-1-1-300x149.jpg",300,149,true],"medium_large":["https:\/\/baycoast.bank\/wp-content\/uploads\/2024\/06\/Promotion-Press-Release-Header-1-1.jpg",600,298,false],"large":["https:\/\/baycoast.bank\/wp-content\/uploads\/2024\/06\/Promotion-Press-Release-Header-1-1.jpg",600,298,false],"1536x1536":["https:\/\/baycoast.bank\/wp-content\/uploads\/2024\/06\/Promotion-Press-Release-Header-1-1.jpg",600,298,false],"2048x2048":["https:\/\/baycoast.bank\/wp-content\/uploads\/2024\/06\/Promotion-Press-Release-Header-1-1.jpg",600,298,false]},"post_excerpt_stackable_v2":"<p>Sala de imprensa \u00b7 28 de Junho, 2024 BayCoast Bank anuncia as promo\u00e7\u00f5es de Almeida, Creador e Lapointe Junta-te a n\u00f3s e felicita os membros da nossa equipa pelas suas merecidas promo\u00e7\u00f5es! SWANSEA, SOMERSET, BERKLEY, FALL RIVER, MA &#8211; O BayCoast Bank(baycoast.bank), um banco de poupan\u00e7a comunit\u00e1rio de longa data que serve as pessoas e as empresas da costa sul de Massachusetts e Rhode Island, tem o prazer de anunciar tr\u00eas promo\u00e7\u00f5es importantes. Sally Almeida, residente em Somerset, Massachusetts, foi elevada ao cargo de Diretora de Recursos Humanos do BayCoast Bank. As suas responsabilidades incluem o processamento de sal\u00e1rios e&hellip;<\/p>\n","category_list_v2":"<a href=\"https:\/\/baycoast.bank\/pt-pt\/.\/sala-de-imprensa\/\" rel=\"category tag\">Sala de imprensa<\/a>","author_info_v2":{"name":"knogueira","url":"https:\/\/baycoast.bank\/pt-pt\/author\/knogueira\/"},"comments_num_v2":"0 comments","publishpress_future_action":{"enabled":false,"date":"2026-05-20 16:15:15","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/baycoast.bank\/pt-pt\/wp-json\/wp\/v2\/posts\/12050","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/baycoast.bank\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/baycoast.bank\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/baycoast.bank\/pt-pt\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/baycoast.bank\/pt-pt\/wp-json\/wp\/v2\/comments?post=12050"}],"version-history":[{"count":0,"href":"https:\/\/baycoast.bank\/pt-pt\/wp-json\/wp\/v2\/posts\/12050\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/baycoast.bank\/pt-pt\/wp-json\/wp\/v2\/media\/11966"}],"wp:attachment":[{"href":"https:\/\/baycoast.bank\/pt-pt\/wp-json\/wp\/v2\/media?parent=12050"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/baycoast.bank\/pt-pt\/wp-json\/wp\/v2\/categories?post=12050"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}