{"id":13131,"date":"2024-03-07T10:13:08","date_gmt":"2024-03-07T15:13:08","guid":{"rendered":"https:\/\/baycoast.bank\/percepcoes\/conversa-com-gary-vierra-vice-presidente-senior-e-diretor-de-riscos-sobre-os-fortes-lacos-da-baycoast-com-a-comunidade\/"},"modified":"2025-07-14T14:43:10","modified_gmt":"2025-07-14T18:43:10","slug":"conversa-com-gary-vierra-vice-presidente-senior-e-diretor-de-riscos-sobre-os-fortes-lacos-da-baycoast-com-a-comunidade","status":"publish","type":"post","link":"https:\/\/baycoast.bank\/pt-pt\/no-ar\/conversa-com-gary-vierra-vice-presidente-senior-e-diretor-de-riscos-sobre-os-fortes-lacos-da-baycoast-com-a-comunidade\/","title":{"rendered":"Conversa com Gary Vierra, vice-presidente s\u00e9nior e diretor de riscos, sobre os fortes la\u00e7os da BayCoast com a comunidade"},"content":{"rendered":"<div class=\"lazyblock-resource-hero-Z2ujvPt wp-block-lazyblock-resource-hero\"><div class=\"noHero\" style=\"height: 10rem;\"><\/div>\n\n<div class=\"spacer\"><\/div>\n\n<div class=\"section\">\n\t<div class=\"smallWrapper gutenberg\">\n\t    \n\t    <div class=\"categories flex\" style=\"justify-content: flex-start;\">\n\t\t\t<div class=\"h6\" style=\"margin-right: 2rem;\"><a href=\"https:\/\/baycoast.bank\/resource\/no-ar\">No ar<\/a><\/div>\n\t\t\t\t\t\t\n\t\t\t<div class=\"primaryColor dot h6\" style=\"transform: scale(2.2); \">\u00b7<\/div>\n\n\t\t\t<div class=\"h6\" style=\"margin-left: 2rem;\">\t\t\t\t7 de Mar\u00e7o, 2024        \n\t\t\t<\/div>\n\t\t<\/div>\n\t    \n\t    <h1 class=\"h2 blue bgWhite\" style=\"max-width: 50rem\">Conversa com Gary Vierra, vice-presidente s\u00e9nior e diretor de riscos, sobre os fortes la\u00e7os da BayCoast com a comunidade<\/h1>\n\t    \n\t    <hr style=\"margin-bottom: 7rem;\">\n\t  \n\t<\/div>\n\t\n\t<div class=\"wrapper\" style=\"justify-content: center; max-width: 90rem;\">\n\t\t<div style=\"width: 100%; position: relative;\">\n\t\t\t<img decoding=\"async\" src=\"https:\/\/baycoast.bank\/wp-content\/uploads\/2024\/02\/Untitled-design-1.jpg\" role=\"img\" aria-label=\"Conversa com Gary Vierra, vice-presidente s\u00e9nior e diretor de riscos, sobre os fortes la\u00e7os da BayCoast com a comunidade\" style=\"width: 100%; height: auto;\" \/>\n  \t\t<\/div>\n\t<\/div>\n<\/div>\n\n          <\/div><div class=\"lazyblock-interior-content-KQzCs wp-block-lazyblock-interior-content\"><div class=\"spacer\"><\/div>\n\n<div class=\"section\">\n\t<div class=\"paddedWrapper\">\n\t\t<div class=\"wrapper flex gutenberg\" style=\"justify-content: center;\">\n\n\t\t\t\n\t\t\t<div class=\"smallWrapper gutenberg\">\n\t\t\t\n\t\t\t\t<div class=\"h3\"><\/div>\n\t\t\t  \n\t\t\t  \t<hr style=\"margin-bottom: 5rem;\">\n\t\t\t\t\n\t\t\t\t\n\n<p>O BayCoast Bank divertiu-se a assistir ao jogo de basquetebol masculino da URI no s\u00e1bado,<em>2<\/em> de mar\u00e7o, quando a equipa defrontou o St. Vamos ouvir a entrevista com Gary Vierra, vice-presidente s\u00eanior e diretor de riscos do banco, sobre os fortes la\u00e7os comunit\u00e1rios do BayCoast. Vais ouvir o que torna o BayCoast t\u00e3o \u00fanico na nossa comunidade e os nossos investimentos substanciais em energias renov\u00e1veis!  <\/p>\n\n\n\n<div class=\"wp-block-stackable-spacer stk-block-spacer stk--no-padding stk-block stk-cc574a4\" data-block-id=\"cc574a4\"><\/div>\n\n\n\n<div style=\"padding:56.25% 0 0 0;position:relative;\"><iframe src=\"https:\/\/player.vimeo.com\/video\/920496487?badge=0&#038;autopause=0&#038;player_id=0&#038;app_id=58479\" frameborder=\"0\" allow=\"autoplay; fullscreen; picture-in-picture; clipboard-write\" style=\"position:absolute;top:0;left:0;width:100%;height:100%;\" title=\"Conversa com Gary Vierra, vice-presidente s\u00e9nior e diretor de riscos, sobre os fortes la\u00e7os da BayCoast com a comunidade\"><\/iframe><\/div><script src=\"https:\/\/player.vimeo.com\/api\/player.js\"><\/script>\n\n\n\t\t\t<\/div>\n\n\t\t<\/div>\n\t<\/div>\n<\/div> <\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":20,"featured_media":11158,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[207],"class_list":["post-13131","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-no-ar"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/baycoast.bank\/wp-content\/uploads\/2024\/02\/Untitled-design-1.jpg",1920,600,false],"thumbnail":["https:\/\/baycoast.bank\/wp-content\/uploads\/2024\/02\/Untitled-design-1-150x150.jpg",150,150,true],"medium":["https:\/\/baycoast.bank\/wp-content\/uploads\/2024\/02\/Untitled-design-1-300x94.jpg",300,94,true],"medium_large":["https:\/\/baycoast.bank\/wp-content\/uploads\/2024\/02\/Untitled-design-1-768x240.jpg",768,240,true],"large":["https:\/\/baycoast.bank\/wp-content\/uploads\/2024\/02\/Untitled-design-1-1024x320.jpg",1024,320,true],"1536x1536":["https:\/\/baycoast.bank\/wp-content\/uploads\/2024\/02\/Untitled-design-1-1536x480.jpg",1536,480,true],"2048x2048":["https:\/\/baycoast.bank\/wp-content\/uploads\/2024\/02\/Untitled-design-1.jpg",1920,600,false]},"post_excerpt_stackable_v2":"<p>No ar \u00b7 7 de Mar\u00e7o, 2024 Conversa com Gary Vierra, vice-presidente s\u00e9nior e diretor de riscos, sobre os fortes la\u00e7os da BayCoast com a comunidade O BayCoast Bank divertiu-se a assistir ao jogo de basquetebol masculino da URI no s\u00e1bado,2 de mar\u00e7o, quando a equipa defrontou o St. Vamos ouvir a entrevista com Gary Vierra, vice-presidente s\u00eanior e diretor de riscos do banco, sobre os fortes la\u00e7os comunit\u00e1rios do BayCoast. Vais ouvir o que torna o BayCoast t\u00e3o \u00fanico na nossa comunidade e os nossos investimentos substanciais em energias renov\u00e1veis!<\/p>\n","category_list_v2":"<a href=\"https:\/\/baycoast.bank\/pt-pt\/.\/no-ar\/\" rel=\"category tag\">No ar<\/a>","author_info_v2":{"name":"kcaisse","url":"https:\/\/baycoast.bank\/pt-pt\/author\/kcaisse\/"},"comments_num_v2":"0 comments","publishpress_future_action":{"enabled":false,"date":"2026-05-20 12:52:03","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/baycoast.bank\/pt-pt\/wp-json\/wp\/v2\/posts\/13131","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/baycoast.bank\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/baycoast.bank\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/baycoast.bank\/pt-pt\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/baycoast.bank\/pt-pt\/wp-json\/wp\/v2\/comments?post=13131"}],"version-history":[{"count":0,"href":"https:\/\/baycoast.bank\/pt-pt\/wp-json\/wp\/v2\/posts\/13131\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/baycoast.bank\/pt-pt\/wp-json\/wp\/v2\/media\/11158"}],"wp:attachment":[{"href":"https:\/\/baycoast.bank\/pt-pt\/wp-json\/wp\/v2\/media?parent=13131"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/baycoast.bank\/pt-pt\/wp-json\/wp\/v2\/categories?post=13131"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}